{"id":292,"date":"2016-01-21T07:29:07","date_gmt":"2016-01-21T06:29:07","guid":{"rendered":"http:\/\/gamma.vflbokel.de\/?page_id=292"},"modified":"2026-04-11T14:29:06","modified_gmt":"2026-04-11T12:29:06","slug":"mai","status":"publish","type":"page","link":"https:\/\/www.vflbokel.de\/alg\/termine\/mai\/","title":{"rendered":"Lauftermine im Mai"},"content":{"rendered":"<h4>Ferien 2025\/2026 in Schleswig-Holstein<\/h4>\n<table style=\"width: 400px;\" border=\"1\" cellspacing=\"0\" align=\"center\">\n<tbody>\n<tr>\n<td style=\"padding: 2px;\">Weihnachten<\/td>\n<td style=\"padding: 2px;\">Ostern<\/td>\n<td style=\"padding: 2px;\">Sommer<\/td>\n<td style=\"padding: 2px;\">Herbst<\/td>\n<\/tr>\n<tr>\n<td style=\"padding: 2px;\">19.12.-06.01.<\/td>\n<td style=\"padding: 2px;\">26.03.-10.04.<\/td>\n<td style=\"padding: 2px;\">04.07.-15.08.<\/td>\n<td style=\"padding: 2px;\">12.10.-24.10.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-334\" src=\"\/alg\/wp-content\/uploads\/Massband.jpg\" alt=\"vermessene Strecke\" width=\"69\" height=\"30\"> = vermessene Strecke<br \/>\n<!--\n\n\n<tr class=\"\">\n\n\n<td>??.05.2015\n\n<img loading=\"lazy\" decoding=\"async\" src=\"..\/..\/res\/neu.gif\" width=\"35\" height=\"34\" border=\"0\" alt=\"neu\" \/><\/td>\n\n\n\n\n<td>100 km:\n07.00 Uhr\n\nMarathon:\n09.00 Uhr<\/td>\n\n\n\n\n<td>49,50 &euro;\n\n25,- &euro;<\/td>\n\n\n\n\n<td><img loading=\"lazy\" decoding=\"async\" src=\"..\/..\/res\/Massband.gif\" width=\"50\" height=\"23\" border=\"0\" align=\"right\" alt=\"Massband\" \/>\n<a href=\"http:\/\/lav-husum.de\/index.php\/veranstaltungen\/100km-von-husum\/ausschreibung-100km-von-husum\" target=\"blank\" rel=\"noopener noreferrer\"><b>100 km von Husum<\/b><\/a>\n\nneu im Programm des au\u00dferordentlich aktiven <b>LAV Husum<\/b> - wem die 100 km zu lang sind, f\u00fcr den wird auch ein Marathon angeboten -\n<b>2014<\/b> sind hier auch gleich die <b>deutschen Meisterschaften<\/b> im 100 km-Lauf<\/td>\n\n\n<\/tr>\n\n\n\n\n\n<tr>\n\n\n<td>??.05.2021<\/td>\n\n\n\n\n<td>09.00 Uhr<\/td>\n\n\n\n\n<td>25,- \u20ac<\/td>\n\n\n\n\n<td><a href=\"http:\/\/www.hohenasper-sc.de\/laufen\/karl-heinz-jost-ultra-marathon\/\" target=\"blank\" rel=\"noopener noreferrer\"><b>14. Karl-Heinz-Jost-Ultramarathon<\/b><\/a>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;\n\n61,5 km - gef\u00fchrter Gruppenlauf ohne Zeitnahme von Husum nach Eckernf\u00f6rde - Lauftempo ca. 7:30 min\/km - Veranstalter ist der SC Hohenaspe - Teilnehmerbegrenzung bei nur 20 L\u00e4ufern - die Startgelder werden f\u00fcr einen gemeinn\u00fctzigen Zweck gespendet.<\/td>\n\n\n<\/tr>\n\n\n\n\n<tr>\n\n\n<td>??.05.2023<\/td>\n\n\n\n\n<td>1,8 km:\n20.00 Uhr\n5,4 km:\n21.00 Uhr\n10,8 km:\n22.30 Uhr<\/td>\n\n\n\n\n<td>4,- \u20ac\n\n8,- \u20ac\n\n11,- \u20ac<\/td>\n\n\n\n\n<td><a href=\"http:\/\/tsvquellenhaupt.de\/index.php\/night-run\" target=\"blank\" rel=\"noopener noreferrer\"><b>5. Nightrun Bornh\u00f6ved<\/b><\/a>\n\n1,8 km, 5,4 km und 10,8 km - der TSV Quellenhaupt Bornh\u00f6ved hat diesen Lauf zum 25. Vereinsjubil\u00e4um ins Leben gerufen und will nach dem gro\u00dfen Erfolg 2016 damit weitermachen - gelaufen wird auf einer 1,8 km-Runde zwischen Sportplatz und Ortskern<\/td>\n\n\n<\/tr>\n\n\n\n\n<tr>\n\n\n<td>??.05.2023<\/td>\n\n\n\n\n<td>5,3 km:\n14.30 Uhr\n11,3 km:\n15.00 Uhr<\/td>\n\n\n\n\n<td>6,- \u20ac\n\n10,- \u20ac<\/td>\n\n\n\n\n<td><a href=\"http:\/\/www.raps-bluetenlauf-ploen.de\/\" target=\"blank\" rel=\"noopener noreferrer\"><b>22. Rapsbl\u00fcten-Lauf Pl\u00f6n<\/b><\/a>\n\n5,3 km und 11,3 km - das volle Programm rund um den <b>Trammer See<\/b> bei Pl\u00f6n - sehr anspruchsvoller Landschaftslauf mit direktem Kontakt zur Natur - starkes Streckenprofil mit vielen H\u00f6henmetern.<\/td>\n\n\n<\/tr>\n\n\n\n\n<tr>\n\n\n<td>??.05.2023<\/td>\n\n\n\n\n<td>5 + 10 km:\n\nab 15.00 Uhr<\/td>\n\n\n\n\n<td>8,- \u20ac<\/td>\n\n\n\n\n<td><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-334\" src=\"\/alg\/wp-content\/uploads\/Massband.jpg\" alt=\"vermessene Strecke\" width=\"69\" height=\"30\"><a href=\"http:\/\/www.nortorfer-stadtlauf.de\/\" target=\"blank\" rel=\"noopener noreferrer\"><b>29. Nortorfer Stadtlauf<\/b><\/a>\n\n5 km und 10 km auf einem 5 km-Rundkurs durch St\u00e4dtchen und Natur - Sch\u00fcler- und Jedermannlauf starten ab 2014 gemeinsam - f\u00fcr Sch\u00fclerInnen ist der Lauf kostenlos, Jugendliche (Jhg. 2004 und \u00e4lter) zahlen nur 3,- Euro - der Gemeindestaffellauf kostet 20,- \u20ac pro Team<\/td>\n\n\n<\/tr>\n\n\n\n\n<tr>\n\n\n<td>??.05.2023<\/td>\n\n\n\n\n<td>16.15 Uhr\n\n17.00 Uhr<\/td>\n\n\n\n\n<td>11,- \u20ac\n\n13,- \u20ac<\/td>\n\n\n\n\n<td><a href=\"http:\/\/campuslauf-kiel.de\/\" target=\"blank\" rel=\"noopener noreferrer\"><b>Intersport Knudsen Campuslauf Kiel<\/b><\/a>\n\n5,4 km und 10,8 km - die 2,7 km lange Strecke f\u00fchrt \u00fcber den Campus der Christian-Albrechts-Universit\u00e4t zu Kiel und ist \u00fcberwiegend flach und barrierefrei. Gelaufen werden 2 oder 4 Runden. Alle Teilnehmerinnen und Teilnehmer erhalten ein Finisher-T-Shirt und bis zum sechsten Platz gibt es Sachpreise.<\/td>\n\n\n<\/tr>\n\n\n\n\n<tr>\n\n\n<td>--.05.2023<\/td>\n\n\n\n\n<td>10.00 Uhr<\/td>\n\n\n\n\n<td>5,- \u20ac<\/td>\n\n\n\n\n<td><a href=\"http:\/\/www.gw-mielkendorf.de\/mielkendorfer-meile\/\" target=\"blank\" rel=\"noopener noreferrer\"><b>19. Mielkendorfer Meile<\/b><\/a>\n<strong><span style=\"color: #ff0000;\">! Auch 2023 abgesagt !<\/span><\/strong>\n\n5,5 km und 10 km - ein kleiner, famili\u00e4rer Lauf wird da in der kleinen <b>Randgemeinde bei Kiel<\/b> jedes Jahr veranstaltet, der aber \u00fcber mehr als eine Meile f\u00fchrt.<\/td>\n\n\n<\/tr>\n\n\n\n\n<tr>\n\n\n<td>??.05.2024<\/td>\n\n\n\n\n<td>ab 09.00 Uhr<\/td>\n\n\n\n\n<td>15,- \u20ac<\/td>\n\n\n\n\n<td><a href=\"https:\/\/www.hohenasper-sc.de\/lauftreff\/steinburg-ultra-marathon\/\" target=\"_blank\" rel=\"noopener noreferrer\"><b>18. Steinburg Marathon<\/b><\/a>\n\nbis zu 50,7 km - gelaufen wird auf einer 8,45 km-Runde - die erste Runde ist ein gef\u00fchrter Gruppenlauf - danach l\u00e4uft jeder sein Tempo - auch k\u00fcrzere Strecken m\u00f6glich - ohne Zeitnahme - ohne Wertung - Veranstalter ist der SC Hohenaspe<\/td>\n\n\n<\/tr>\n\n\n\n\n<tr>\n\n\n<td>??.05.2024<\/td>\n\n\n\n\n<td>ab 10.00 Uhr<\/td>\n\n\n\n\n<td>20,- \u20ac\n\n10,- \u20ac\n\n13,- \u20ac<\/td>\n\n\n\n\n<td><a href=\"http:\/\/my.raceresult.com\/118356\/?lang=de\" target=\"blank\" rel=\"noopener noreferrer\"><b>2. Kalkgrubenlauf<\/b><\/a> in Klein Nordende\n<b> ! 2024 mal wieder geplant ??  <\/b>\n\n5 km und 10 km - Das Naturschutzgebiet Liether Kalkgrube im Elmshorner Vorort ist eine einmalige geologische und \u00f6kologische Besonderheit - durch das umliegende Naturschutzgebiet geht seit 2019 dieser neue Volkslauf - schon zur Premiere kamen \u00fcber 330 Ausdauersportler - beide Strecken k\u00f6nnen auch gewalkt werden.<\/td>\n\n\n<\/tr>\n\n\n\n\n<tr>\n\n\n<td>??.05.2024<\/td>\n\n\n\n\n<td>5 km:\n10.00 Uhr\n10,7 km:\n10.10 Uhr<\/td>\n\n\n\n\n<td>8,- \u20ac<\/td>\n\n\n\n\n<td><b><a href=\"http:\/\/www.bosauer-sv.de\/ausschreibung.htm\" target=\"_blank\" rel=\"noopener noreferrer\">20. Bosauer Volkslauf<\/a><\/b>\n\n<b> ? Auch f\u00fcr 2024 abgesagt ? <\/b>\n5 km und 10,7 km - die Gemeinde am <b>Pl\u00f6ner See<\/b> \u00fcberzeugt mit einer anspruchsvollen und landschaftlich sehr sch\u00f6nen Strecke. Und ein Platz auf dem Treppchen ist hier nicht so schwer zu erreichen.<\/td>\n\n\n<\/tr>\n\n\n\n\n<tr>\n\n\n<td>??.05.2025<\/td>\n\n\n\n\n<td>09.30 Uhr<\/td>\n\n\n\n\n<td>ab 35,- \u20ac<\/td>\n\n\n\n\n<td><img loading=\"lazy\" decoding=\"async\" width=\"69\" height=\"30\" class=\"alignnone size-full wp-image-334\" alt=\"vermessene Strecke\" src=\"\/alg\/wp-content\/uploads\/Massband.jpg\"><a href=\"https:\/\/kalender.shlv.de\/ausschreibungen\/20240526_3_ass_LMMarathon_Husum.pdf\" target=\"blank\" rel=\"noopener noreferrer\"><b>2. Marathon am Meer<\/b><\/a> in  Husum ??\n\nder Wintermarathon war Kult, aber ist nicht mehr - jetzt wird im Fr\u00fchjahr gelaufen - die Strecke abwechslungsreich und anspruchsvoll durch die D\u00f6rfer n\u00f6rdlich von Husum - Start und Ziel sind in Husum\/Schob\u00fcll, Nordseestr. 35 .<\/td>\n\n\n<\/tr>\n\n\n\n\n--><\/p>\n<table border=\"1\" cellspacing=\"0\" align=\"center\">\n<tbody>\n<tr class=\"u\">\n<th width=\"90\">Datum<\/th>\n<th width=\"90\">Startzeit<\/th>\n<th width=\"100\">Startgeld<\/th>\n<th width=\"570\">Veranstaltung<\/th>\n<\/tr>\n<tr>\n<td>01.05.2026<\/td>\n<td>ab 10.00 Uhr<\/td>\n<td>8,- \u20ac<\/p>\n<p>11,- \u20ac<\/p>\n<p>12,50 \u20ac<\/td>\n<td><a href=\"http:\/\/www.meldorfer-brueckenlauf.de\/\" target=\"blank\" rel=\"noopener noreferrer\"><b>16. Meldorfer Br\u00fcckenlauf \/ Westk\u00fcsten-Halbmarathon<\/b><\/a><\/p>\n<p>6 km, 9 km und HM an der Westk\u00fcste &#8211; 6 km auch als (Nordic) Walking &#8211; der Lauf in der Dithmarscher Domstadt hat sich mittlerweile in der Region etabliert.<\/td>\n<\/tr>\n<tr>\n<td>01.05.2026<\/td>\n<td>5 km:<br \/>\n10.00 Uhr<br \/>\n10 km:<br \/>\n11.45 Uhr<\/td>\n<td>8,- \u20ac<\/p>\n<p>10,- \u20ac<\/td>\n<td><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-334\" src=\"\/alg\/wp-content\/uploads\/Massband.jpg\" alt=\"vermessene Strecke\" width=\"69\" height=\"30\"><a href=\"http:\/\/www.kaltenkirchener-stadtlauf.de\/\" target=\"blank\" rel=\"noopener noreferrer\"><b>36. Kaltenkirchener Stadtlauf<\/b><\/a><\/p>\n<p>flach, schnell auf 5 km-Rundkurs und immer gut besucht, vor allem von leistungsstarken L\u00e4ufern aus der Metropole Hamburg und ihrem Umland &#8211; 5 km auch f\u00fcr Walker &#8211; Zeitmessung mit einem Einweg-Chip, der nicht zur\u00fcckgegeben werden muss.<\/td>\n<\/tr>\n<tr>\n<td>02.05.2026<\/td>\n<td>5 km:<br \/>\n09.30 Uhr<br \/>\n10 km:<br \/>\n10.00 Uhr<br \/>\nHM:<br \/>\n09.45 Uhr<\/td>\n<td>8,- \u20ac<\/p>\n<p>10,- \u20ac<\/p>\n<p>14,- \u20ac<\/td>\n<td><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-334\" src=\"\/alg\/wp-content\/uploads\/Massband.jpg\" alt=\"vermessene Strecke\" width=\"69\" height=\"30\"><a href=\"https:\/\/www.suedenseelauf.de\/suedenseelauf\/anmeldung-schueler-teamlauf-2018-2\/\" target=\"blank\" rel=\"noopener noreferrer\"><b>14. S\u00fcdenseelauf in S\u00f6rup<\/b><\/a><\/p>\n<p>5 km, 10 km und HM &#8211; da geht es rund um den S\u00fcdensee &#8211; der HM ist amtlich vermessen &#8211; 2012 haben immerhin 515 Interessierte den Weg in diesen kleinen Ort zwischen Flensburg und Kappeln gefunden &#8211;<br \/>\nseit 2013 deshalb regelm\u00e4\u00dfig im <a href=\"https:\/\/www.zippels.de\/events\/nord-cup\/\" target=\"blank\" rel=\"noopener noreferrer\"><b>Zippels Nord-Cup<\/b> <\/a><\/td>\n<\/tr>\n<p><!--\n\n\n<tr>\n\n\n<td>03.05.2024<\/td>\n\n\n\n\n<td>5,4 km:\n10.00 Uhr\n11,3 km:\n09.50 Uhr<\/td>\n\n\n\n\n<td>ab 10,- \u20ac<\/td>\n\n\n\n\n<td><a href=\"http:\/\/www.sfco.de\/Veranstaltungen\/Ottendorfer-Kanallauf\/\" target=\"blank\" rel=\"noopener noreferrer\"><b>26. Ottendorfer Kanallauf<\/b><\/a>\n\n\n<p style=\"text-align: center;\"><strong>! F\u00fcr 2023 ebenfalls abgesagt !<\/strong><\/p>\n\n\n\n5,4 km und 11,3 km - anspruchsvolle und sch\u00f6ne Strecke durch die Mor\u00e4nenlandschaft westlich von Kiel. Von Ottendorf zum <b>Nord-Ostsee-Kanal<\/b>, ein St\u00fcck am Kanal entlang und auf anderem Wege zur\u00fcck in den Ort - Sch\u00fcler und Jugendliche bis 19 J. zahlen die H\u00e4lfte.<\/td>\n\n\n<\/tr>\n\n\n--><\/p>\n<tr>\n<td>03.05.2026<\/td>\n<td>ab 09.00 Uhr<\/td>\n<td>\n2,6 km: 4,- \u20ac<br \/>\n5 km: 8,- \u20ac<br \/>\n10 km: 11,- \u20ac<\/td>\n<td><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-334\" src=\"\/alg\/wp-content\/uploads\/Massband.jpg\" alt=\"vermessene Strecke\" width=\"69\" height=\"30\"><a href=\"https:\/\/svholtsee.de\/wp-content\/uploads\/2023\/10\/ausschreibung-holtsee-lauf-2024-stand-26.10.2023.pdf\" target=\"_blank\" rel=\"noopener noreferrer\"><b>3. Holtsee-Lauf<\/b><\/a> &#8211; <b>Wertungslauf zum <a href=\"https:\/\/www.zippels.de\/events\/kiel-cup\/\" target=\"blank\" rel=\"noopener noreferrer\">Zippel&#8217;s Kiel-Cup<\/a><\/b><\/p>\n<p>2,6 km Sch\u00fclerlauf, 5 km, 10 km &#8211; ein neuer Volkslauf im Zentrum von Schleswig-Holstein auf einem reizvollen Kurs durch den  Naturpark \u201eH\u00fcttener Berge\u201c. Die Strecke verf\u00fcgt \u00fcber leichte Anstiege und eine wundersch\u00f6ne Landschaft &#8211; die 10 km-Strecke ist offiziell vermessen.<\/td>\n<\/tr>\n<tr>\n<td>03.05.2026<\/td>\n<td>ab 10.15 Uhr<\/td>\n<td>5 km:<br \/>\n9,- \u20ac<br \/>\n10 km:<br \/>\n16,- \u20ac<br \/>\nHM:<br \/>\n26,- \u20ac<\/td>\n<td><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-334\" src=\"\/alg\/wp-content\/uploads\/Massband.jpg\" alt=\"vermessene Strecke\" width=\"69\" height=\"30\"><a href=\"http:\/\/www.ostseekuestenlauf.de\" target=\"blank\" rel=\"noopener noreferrer\"><b>43. Ostseek\u00fcstenlauf<\/b><\/a><\/p>\n<p>5 km, 10 km und HM &#8211; ein weiterer interessanter Lauf in Mecklenburg-Vorpommern &#8211; das alte Seebad K\u00fchlungsborn kann mit einem komfortablen Campingplatz und maritimen Flair aufwarten &#8211; Grund genug, dort auch mal ein L\u00e4ufchen zu absolvieren &#8211; seit 2021 sind Start und Ziel nicht mehr in K\u00fchlungsborn sondern am Sportplatz in Rerik.<\/td>\n<\/tr>\n<tr>\n<td>06.+07.05.2026<\/td>\n<td>18.00 Uhr<\/td>\n<td>ab 22,- \u20ac<\/td>\n<td><a href=\"https:\/\/www.businessrun-zippels.de\/kiel\/\" target=\"blank\" rel=\"noopener noreferrer\"><b>AOK Businessrun<\/b><\/a> in Kiel<\/p>\n<p>4,5 km entlang der Kiellinie am Westufer der Kieler F\u00f6rde &#8211; Start ist vor dem Landeshaus, Ziel an der Reventlouwiese &#8211; jedes Jahr sind mehrere Tausend Teilnehmende dabei.<\/td>\n<\/tr>\n<tr>\n<td>08.05.2026<\/td>\n<td>ab 17.30 Uhr<\/td>\n<td>15,- \u20ac \/<br \/>\n17,- \u20ac<\/td>\n<td><a href=\"http:\/\/www.luebecker-frauenlauf.de\/\" target=\"blank\" rel=\"noopener noreferrer\"><b>28. L\u00fcbecker Frauenlauf<\/b><\/a><\/p>\n<p>5,2 km und 10,5 km &#8211; beide Strecken f\u00fchren auf Wanderwegen am Elbe-L\u00fcbeck-Kanal entlang, Start und Ziel sind im <b>Stadion Buniamshof<\/b> &#8211; die 5,2 km k\u00f6nnen auch gewalkt werden &#8211; Ein T-Shirt ist (f\u00fcr die ersten 250 Anmelderinnen) im Startgeld enthalten.<\/td>\n<\/tr>\n<tr>\n<td>08.05.2026<\/td>\n<td>5 km:<br \/>\n18.00 Uhr<br \/>\n10 km:<br \/>\n19.00 Uhr<br \/>\nM:<br \/>\n13.00 Uhr<\/td>\n<td>8,- \u20ac<\/p>\n<p>10,- \u20ac<\/p>\n<p>20,- \u20ac<\/td>\n<td><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-334\" src=\"\/alg\/wp-content\/uploads\/Massband.jpg\" alt=\"vermessene Strecke\" width=\"69\" height=\"30\" \/><a href=\"http:\/\/hu-l\u00e4uft.de\/\" target=\"blank\" rel=\"noopener noreferrer\"><b>17. Henstedt-Ulzburg l\u00e4uft<\/b><\/a><\/p>\n<p>5 km und 10 km &#8211; 2008 war <b>Volkslauf-Premiere<\/b> mit \u00fcber 500 Finishern,<br \/>\n2016 kamen fast 2000 L\u00e4ufer in die gro\u00dfe Gemeinde im Hamburger Umland &#8211; 2017 gab es zum Jubil\u00e4um einen Marathon.<\/td>\n<\/tr>\n<tr>\n<td>09.05.2026<\/td>\n<td>ab 09.00 Uhr<\/td>\n<td>50,- \u20ac<\/td>\n<td><a href=\"https:\/\/www.helgoland-marathon.com\/\" target=\"blank\" rel=\"noopener noreferrer\"><b>27. Helgoland-Marathon<\/b><\/a><\/p>\n<p>jeder Winkel der kleinen deutschen <b>Hochseeinsel<\/b> wird ausgenutzt, um die 42,195 km innerhalb von vier Runden unterzubringen &#8211; und jedesmal der harte Anstieg zum Oberland, der dann mit einer grandiosen Aussicht belohnt wird &#8211; f\u00fcr Familien gibt es seit einiger Zeit auch einen &#8222;Mini-Marathon&#8220; \u00fcber nur 5,8 km.<\/td>\n<\/tr>\n<tr>\n<td>09.05.2026<\/td>\n<td>5 km:<br \/>\nab 14.00 Uhr<br \/>\n10 km:<br \/>\n18.00 Uhr<br \/>\nHM:<br \/>\n15.30 Uhr<\/td>\n<td>14,- \u20ac<\/p>\n<p>16,- \u20ac<\/p>\n<p>24,- \u20ac<\/td>\n<td><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-334\" src=\"\/alg\/wp-content\/uploads\/Massband.jpg\" alt=\"vermessene Strecke\" width=\"69\" height=\"30\"><a href=\"http:\/\/www.stoerlauf.de\/\" target=\"blank\" rel=\"noopener noreferrer\"><b>26. St\u00f6rlauf Itzehoe<\/b><\/a><\/p>\n<p>5 km, 10 km und HM &#8211; Achtung, vor allem der HM ist schon immer zeitig ausgebucht, also mit der Meldung nicht bis zum letzten Moment warten &#8211;<br \/>\n\u00fcber 5 km gibt es von 14.00 Uhr bis 17.00 Uhr vier Starts im Stundentakt &#8211;<br \/>\n5 + 10 km werden auch f\u00fcr Walker angeboten &#8211;<br \/>\nWertungslauf zum <a href=\"http:\/\/steinburgcup.de\/pages\/die-veranstalter.php\" target=\"blank\" rel=\"noopener noreferrer\"><b>Steinburg-Cup<\/b><\/a><\/td>\n<\/tr>\n<tr>\n<td>10.05.2026<\/td>\n<td>5 km:<br \/>\n09.15 Uhr<br \/>\n10 km:<br \/>\n10.00 Uhr<br \/>\nHM:<br \/>\n10.30 Uhr<\/td>\n<td>13,-\/18,-\/19,- \u20ac<\/td>\n<td><a href=\"https:\/\/www.groemitz.de\/sun-run\" target=\"blank\" rel=\"noopener noreferrer\"><b>21. Gr\u00f6mitzer SUN RUN<\/b><\/a><\/p>\n<p>5 km, 10 km, HM und ein 3,33 km-Sch\u00fclerlauf (9,- \u20ac, 11:15 Uhr) &#8211; ein umfangreiches Programm, das die <b>Ostsee-Gemeinde<\/b> seit ein paar Jahren zu organisieren hat, denn zus\u00e4tzlich gibt es auch noch Walkingstrecken &#8211; ein SunRun-T-Shirt ist im Startgeld enthalten<\/td>\n<\/tr>\n<tr>\n<td>10.05.2026<\/td>\n<td>ab 10.00 Uhr<\/td>\n<td>5 km: 12,- \u20ac<br \/>\n10 km: 22,- \u20ac<br \/>\nHM: 28,- \u20ac<\/td>\n<td><a href=\"https:\/\/www.wedel-halbmarathon.de\/infos\/\" target=\"_blank\" rel=\"noopener noreferrer\"><b>9. Wedeler Halbmarathon<\/b><\/a><\/p>\n<p>5 km, 10 km und HM &#8211; ein Volkslauf im S\u00fcdwesten von Schleswig-Holstein auf einem reizvollen Rundkurs durch die Elbmarsch, Teile von Holm sowie durch Wedel.<\/td>\n<\/tr>\n<tr>\n<td>10.05.2026<\/td>\n<td>2,6 km:<br \/>\n10.00 Uhr<br \/>\n5 km:<br \/>\n10.40 Uhr<br \/>\n10 km:<br \/>\n11.20 Uhr<\/td>\n<td>6,- \u20ac<\/p>\n<p>10,- \u20ac<\/p>\n<p>12,- \u20ac<\/td>\n<td><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-334\" src=\"\/alg\/wp-content\/uploads\/Massband.jpg\" alt=\"vermessene Strecke\" width=\"69\" height=\"30\"><a href=\"https:\/\/www.niebueller-stadtlauf.de\/ausschreibung\/\" target=\"blank\" rel=\"noopener noreferrer\"><b>30. Stadtwerkelauf Nieb\u00fcll <\/b><\/a><\/p>\n<p>2,6 km, 5 km und 10 km &#8211; die Gemeinde in <b>Nordfriesland<\/b> ist bekannt durch ihren Verladebahnhof f\u00fcr die Autoreisez\u00fcge nach Sylt. Nat\u00fcrlich wird hier auch gelaufen, die LG Nieb\u00fcll-S\u00fcderl\u00fcgum hat in Schleswig-Holstein einen hervorragenden Ruf &#8211; Wertungslauf zum <a href=\"https:\/\/www.zippels.de\/events\/nord-cup\/\" target=\"blank\" rel=\"noopener noreferrer\"><b>Zippel\u00b4s Nord-Cup<\/b><\/a><\/td>\n<\/tr>\n<tr>\n<td>10.05.2026<\/td>\n<td>5 km:<br \/>\n09.30 Uhr<br \/>\n10 km:<br \/>\n10.30 Uhr<\/td>\n<td>6\/11,- \u20ac<\/td>\n<td><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-334\" src=\"\/alg\/wp-content\/uploads\/Massband.jpg\" alt=\"vermessene Strecke\" width=\"69\" height=\"30\"><a href=\"http:\/\/www.spiridon-schleswig.de\" target=\"blank\" rel=\"noopener noreferrer\"><b>38. Schleswiger Stadtlauf<\/b><\/a><\/p>\n<p><b>! 2026 mit Landesmeisterschaften im 5 + 10 km-Stra\u00dfenlauf !<\/b><\/p>\n<p>5 km und 10 km &#8211; der Traditionslauf der Schleistadt pr\u00e4sentierte sich 2006 erstmals auf einer neuen Strecke: ein 5 km-Rundkurs im Bereich von Schlei und Altstadt &#8211; das Konzept scheint sich bew\u00e4hrt zu haben &#8211;<br \/>\nWertungslauf zum <b><a href=\"https:\/\/www.zippels.de\/events\/nord-cup\/\" target=\"blank\" rel=\"noopener noreferrer\"> Zippel\u00b4s Nord-Cup<\/a><\/b><\/td>\n<\/tr>\n<tr>\n<td>1?.05.2026<\/td>\n<td>18.00 Uhr<\/td>\n<td>3,- \u20ac<\/td>\n<td><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-334\" src=\"\/alg\/wp-content\/uploads\/Massband.jpg\" alt=\"vermessene Strecke\" width=\"69\" height=\"30\"><a href=\"http:\/\/www.klv-sl-fl.de\/\" target=\"blank\" rel=\"noopener noreferrer\"><b>26. Angeliter Laufserie<\/b><\/a><\/p>\n<p>1. Lauf: 1500 m und 800 m &#8211; der Kreisleichtathletik-Verband Schleswig-Flensburg veranstaltet diese Bahnlaufserie seit einigen Jahren an wechselnden Veranstaltungsorten Mittwochs abends &#8211; zum 1. Lauf l\u00e4dt Gelting ein.<\/td>\n<\/tr>\n<tr>\n<td>16.05.2026<\/td>\n<td>5 km:<br \/>\n15.40 Uhr<br \/>\n10 km:<br \/>\n18.00 Uhr<\/td>\n<td>28,- \u20ac<\/td>\n<td><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-334\" src=\"\/alg\/wp-content\/uploads\/Massband.jpg\" alt=\"vermessene Strecke\" width=\"69\" height=\"30\"><a href=\"http:\/\/www.berliner-frauenlauf.de\" target=\"blank\" rel=\"noopener noreferrer\"><b>41. Frauenlauf Berlin<\/b><\/a><\/p>\n<p>5 km Fun-Run, wahlweise mit oder ohne Zeitmessung und 10 km &#8211; beim <b>gr\u00f6\u00dften Frauenlauf Deutschlands<\/b> d\u00fcrfen M\u00e4nner nur zuschauen, anfeuern, essen und trinken &#8211; mit gro\u00dfem Rahmenprogramm vor dem Brandenburger Tor &#8211; und f\u00fcr jede Starterin gibt es ein Kosmetik-Sortiment gratis &#8211; wie jedes Jahr!<\/td>\n<\/tr>\n<tr>\n<td>17.05.2026<\/td>\n<td>HM:<br \/>\n10.00 Uhr<br \/>\n10 km:<br \/>\n10.00 Uhr<br \/>\n7 km:<br \/>\n14.00 Uhr<br \/>\n3 km:<br \/>\n13:15\n<\/td>\n<td>37,- \u20ac<\/p>\n<p>25,- \u20ac<\/p>\n<p>18,- \u20ac<\/p>\n<p>10,- \u20ac\n<\/td>\n<td><a href=\"http:\/\/www.rostocker-citylauf.de\/\" target=\"blank\" rel=\"noopener noreferrer\"><b>34. Rostocker Citylauf<\/b><\/a><\/p>\n<p>3 km, 7 km, 10 km und HM &#8211; der veranstaltende LAV Rostock hat hervorragende Athleten in seinen Reihen &#8211; und auch beim Citylauf sind die 10 km unter 30 min keine Seltenheit &#8211; ein echter Citylauf auf einem 3 km-Rundkurs.<\/td>\n<\/tr>\n<tr>\n<td>17.05.2026<\/td>\n<td>ab 09.30 Uhr<\/td>\n<td>16,- \u20ac<\/td>\n<td><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-334\" src=\"\/alg\/wp-content\/uploads\/Massband.jpg\" alt=\"vermessene Strecke\" width=\"69\" height=\"30\"><a href=\"http:\/\/fischhallen-lauf.de\/\" target=\"blank\" rel=\"noopener noreferrer\"><b>20. Ostufer Fischhallen-Lauf<\/b><\/a><\/p>\n<p>5 km-Sch\u00fclerlauf (8,- \u20ac) und 10 km-Hauptlauf &#8211; seit dem gro\u00dfen Erfolg bei der Premiere 2005 musste dieser Lauf einfach zur st\u00e4ndigen Einrichtung werden &#8211;<br \/>\nes geht durch Bereiche am <b>Kieler Ostufer<\/b>, die man sonst nicht so schnell zu sehen bekommt und betreten darf: Arsenal und Fischhalle &#8211; 5 km auch f\u00fcr Walker.<\/td>\n<\/tr>\n<tr>\n<td>??.05.2026<\/td>\n<td>ab 18.00 Uhr<\/td>\n<td>3,- \u20ac<\/td>\n<td><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-334\" src=\"\/alg\/wp-content\/uploads\/Massband.jpg\" alt=\"vermessene Strecke\" width=\"69\" height=\"30\"><a href=\"http:\/\/www.klv-sl-fl.de\/\" target=\"blank\" rel=\"noopener noreferrer\"><b>26. Angeliter Laufserie<\/b><\/a>&nbsp;<\/p>\n<p>2. Lauf: 3000 m und 1000 m &#8211; der Kreisleichtathletik-Verband Schleswig-Flensburg veranstaltet diese Bahnlaufserie seit vielen Jahren an wechselnden Veranstaltungsorten Mittwochs abends &#8211; dieser 2. Lauf findet in Schleswig statt.<\/td>\n<\/tr>\n<tr>\n<td>21.05.2026<\/td>\n<td>ab 18.15 Uhr<\/td>\n<td>6,-\/10,- \u20ac<\/td>\n<td><a href=\"http:\/\/ssv-bredenbek.de\/\" target=\"blank\" rel=\"noopener noreferrer\"><b>24. Bredenbeker Waldlauf<\/b><\/a><\/p>\n<p>5,9 km und 10,6 km &#8211; auch 2024 wird wieder ein <b>Halbmarathon<\/b> angeboten &#8211; ein Donnerstagabendlauf und gar nicht weit von uns entfernt: und traditionell treten die Aktiven der ALG hier immer in gro\u00dfer Besetzung auf und erreichen vordere Platzierungen &#8211; 2022 z.B. die ersten drei Pl\u00e4tze beim HM.<\/td>\n<\/tr>\n<tr>\n<td>23.05.2026<\/td>\n<td>12.30 Uhr<\/td>\n<td>Erw. 25,- \u20ac<br \/>\nJug. 15,- \u20ac<\/td>\n<td><a href=\"http:\/\/amrumer-mukolauf.de\/\" target=\"blank\" rel=\"noopener noreferrer\"><b>23. Amrumer Mukoviszidoselauf<\/b><\/a><\/p>\n<p>4,5 km, 13,5 km und 26 km &#8211; der Lauf dient einem guten Zweck: Die Einnahmen aus den Startgeldern kommen der Regionalgruppe Amrum des <b>Mukoviszidose e.V. <\/b> und den Patienten der &#8222;Fachklinik Satteld\u00fcne&#8220; zugute &#8211; 2024 kamen sensationelle 55 000 \u20ac zusammen &#8211; und ein L\u00e4ufer-T-Shirt ist im Startgeld inbegriffen &#8211; auch Sponsoren sind immer herzlich willkommen.<\/td>\n<\/tr>\n<tr>\n<td>24.05.2025<\/td>\n<td>Zeitplan<br \/>\nsiehe<br \/>\nSHLV<\/td>\n<td>nach SHLV<\/td>\n<td><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-334\" src=\"\/alg\/wp-content\/uploads\/Massband.jpg\" alt=\"vermessene Strecke\" width=\"69\" height=\"30\"><span style=\"color: #ff0000;\"><b>! <\/b><\/span><a href=\"https:\/\/kalender.shlv.de\/ausschreibungen\/20250524_SHLV_ass_LMLangstrecken_Hamburg.pdf\" target=\"_blank\" rel=\"noopener noreferrer\"><b>Landesmeisterschaften Langstrecken<\/b><\/a><span style=\"color: #ff0000;\"><b> !<\/b><\/span><\/p>\n<p>nur f\u00fcr M\u00e4nner, Frauen, MJ\/WJ U16, U18, U20 &#8211; dieses Jahr in Hamburg, Jahnkampfbahn, Linnering 3 &#8211; die Jugendlichen laufen 2000 m oder 3000 m.<\/td>\n<\/tr>\n<tr>\n<td>29.05.2026<\/td>\n<td>ab 18.00 Uhr<\/td>\n<td>10,- \u20ac<\/td>\n<td><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-334\" src=\"\/alg\/wp-content\/uploads\/Massband.jpg\" alt=\"vermessene Strecke\" width=\"69\" height=\"30\"><b><a href=\"https:\/\/www.mtv-burg.de\/neuigkeiten.html\" target=\"blank\" rel=\"noopener noreferrer\">37. Lauf rund um Burg<\/a><\/b><\/p>\n<p>4,6 km und 10 km &#8211; der Freitagabend geh\u00f6rt dem St\u00e4dtchen Burg in Dithmarschen &#8211; Wertungslauf zum <a href=\"http:\/\/www.klv-dithmarschen.net\/\" target=\"blank\" rel=\"noopener noreferrer\"><b>Dithmarschen-Cup<\/b><\/a><\/td>\n<\/tr>\n<tr>\n<td>30.05.2026<\/td>\n<td>5,6 km:<br \/>\n17.15 Uhr<br \/>\n10 km:<br \/>\n17.35 Uhr<\/td>\n<td>10,- \u20ac<\/p>\n<p>15,- \u20ac<\/td>\n<td><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-334\" src=\"\/alg\/wp-content\/uploads\/Massband.jpg\" alt=\"vermessene Strecke\" width=\"69\" height=\"30\"><a href=\"http:\/\/www.tsv-stocksee.de\/\" target=\"_blank\" rel=\"noopener noreferrer\"><b>31. Stockseer Abendlauf<\/b><\/a><\/p>\n<p>5,6 km + 10 km &#8211; Jugendliche bis 18 Jahre zahlen nur die H\u00e4lfte &#8211; die 10 km sind jetzt nach DLV vermessen &#8211;<br \/>\n auf einer tollen, abwechslungsreichen und reizvollen Strecke geht es um den <b>Stocksee<\/b> herum, \u00fcberwiegend auf Waldwegen &#8211; 2022 fand der Abendlauf als Spendenlauf zugunsten der Fl\u00fcchtlinge aus der Ukraine statt.<\/td>\n<\/tr>\n<tr>\n<td>30.05.2026<\/td>\n<td>09.00 Uhr<\/td>\n<td>ab 379,- \u20ac<\/td>\n<td><b><a href=\"http:\/\/www.laufzwischendenmeeren.de\/\" target=\"blank\" rel=\"noopener noreferrer\">19. Lauf zwischen den Meeren<\/a><\/b><\/p>\n<p>das geistige Kind von <a href=\"http:\/\/www.thomas-wessinghage.de\/\" target=\"blank\" rel=\"noopener noreferrer\"><b>Thomas Wessinghage<\/b><\/a>, jetzt ist Rainer Ziplinski federf\u00fchrend &#8211; ein Staffellauf f\u00fcr 5 &#8211; 10 Pers.\/Staffel von Husum an der Nordsee bis zur <b>Kurklinik Damp<\/b> an der Ostsee \u00fcber 10 Etappen &#8211; 2024  zwischen 6,2 km und 11,5 km mit 89,4 km Gesamtl\u00e4nge &#8211; hohe Startgeb\u00fchren, wertvolle Preise f\u00fcr die f\u00fcnf besten Teams, umfangreiches Rahmenprogramm und das Ganze dient auch noch einem guten Zweck.<\/td>\n<\/tr>\n<tr>\n<td>31.05.2026<\/td>\n<td>laut Zeitplan<\/td>\n<td>nach SHLV<\/td>\n<td><span style=\"color: #ff0000; font-size: small;\"><b>!<\/b><\/span><a href=\"https:\/\/kalender.shlv.de\/ausschreibungen\/20260531_SHLV_ass_LMMasters_Kiel.pdf\" target=\"blank\" rel=\"noopener noreferrer\"> <b>Leichtathletik-Landesmeisterschaften f\u00fcr Senioren in Kiel<\/b><\/a><span style=\"color: #ff0000; font-size: small;\"><b>!<\/b><\/span><\/p>\n<p>Laufwettbewerbe von 100 m bis 3000 m &#8211; Sprung- und Wurfdisziplinen &#8211; gemeinsam mit Hamburg &#8211; n\u00e4here Infos auf der Website des SHLV.<\/td>\n<\/tr>\n<tr class=\"tu\">\n<td>31.05.2026<\/td>\n<td>10.00 Uhr<\/td>\n<td>5,-\/10,- &euro;<br \/>\n(als Spende)<\/td>\n<td>\n <b><a href=\"https:\/\/fcstpauli-marathon.de\/lauf-gegen-rechts-2026\/\" target=\"blank\" rel=\"noopener noreferrer\">15. Lauf gegen Rechts<\/a><\/b><\/p>\n<p>7,4 km um die Au\u00dfenalster &#8211; es geht darum, ein Zeichen zu setzen gegen die Gefahr eines sich ausbreitenden Faschismus und gegen international sich immer weiter verst\u00e4rkende Tendenzen eines demokratiefeindlichen Weltbildes &#8211;<br \/>\ndie Zeitnahme \u00fcbernimmt jeder selber, es kann auch auf einer selbstgew\u00e4hlten Strecke gelaufen werden &#8211; erwartet wird eine Spende von 5 bzw. 10 Euro, Startnummernausdruck geht am eigenen PC, Ergebnislisten gibt es nicht &#8211; Veranstalter ist der <b>FC St. Pauli<\/b>.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>Ferien 2025\/2026 in Schleswig-Holstein Weihnachten Ostern Sommer Herbst 19.12.-06.01. 26.03.-10.04. 04.07.-15.08. 12.10.-24.10. = vermessene Strecke Datum Startzeit Startgeld Veranstaltung 01.05.2026 ab 10.00 Uhr 8,- \u20ac 11,- \u20ac 12,50 \u20ac 16. Meldorfer Br\u00fcckenlauf \/ Westk\u00fcsten-Halbmarathon 6 km, 9 km und HM an der Westk\u00fcste &#8211; 6 km auch als (Nordic) Walking &#8211; der Lauf in der &hellip; <a href=\"https:\/\/www.vflbokel.de\/alg\/termine\/mai\/\" class=\"more-link\"><span class=\"screen-reader-text\">Lauftermine im Mai<\/span> weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"parent":8,"menu_order":2,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-292","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.vflbokel.de\/alg\/wp-json\/wp\/v2\/pages\/292","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vflbokel.de\/alg\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.vflbokel.de\/alg\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.vflbokel.de\/alg\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vflbokel.de\/alg\/wp-json\/wp\/v2\/comments?post=292"}],"version-history":[{"count":210,"href":"https:\/\/www.vflbokel.de\/alg\/wp-json\/wp\/v2\/pages\/292\/revisions"}],"predecessor-version":[{"id":9459,"href":"https:\/\/www.vflbokel.de\/alg\/wp-json\/wp\/v2\/pages\/292\/revisions\/9459"}],"up":[{"embeddable":true,"href":"https:\/\/www.vflbokel.de\/alg\/wp-json\/wp\/v2\/pages\/8"}],"wp:attachment":[{"href":"https:\/\/www.vflbokel.de\/alg\/wp-json\/wp\/v2\/media?parent=292"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}